{"id":16128,"date":"2025-09-30T13:24:38","date_gmt":"2025-09-30T11:24:38","guid":{"rendered":"https:\/\/agorafabrics.com\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/"},"modified":"2026-02-27T15:32:43","modified_gmt":"2026-02-27T14:32:43","slug":"stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori","status":"publish","type":"post","link":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/","title":{"rendered":"Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"16128\" class=\"elementor elementor-16128 elementor-16118\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb858c1 e-flex e-con-boxed e-con e-parent\" data-id=\"eb858c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca53d85 elementor-widget elementor-widget-image\" data-id=\"ca53d85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"54\" src=\"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Logo-Life-Verde-300x54.png\" class=\"attachment-medium size-medium wp-image-16554 wvs-archive-product-image\" alt=\"\" srcset=\"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Logo-Life-Verde-300x54.png 300w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Logo-Life-Verde-1024x183.png 1024w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Logo-Life-Verde-768x137.png 768w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Logo-Life-Verde-1536x275.png 1536w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Logo-Life-Verde-2048x366.png 2048w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Logo-Life-Verde-600x107.png 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" loading=\"eager\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2d6bf7 elementor-widget elementor-widget-image\" data-id=\"b2d6bf7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8.jpg\" class=\"attachment-full size-full wp-image-27874 wvs-archive-product-image\" alt=\"\" srcset=\"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8.jpg 2560w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8-300x200.jpg 300w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8-1024x683.jpg 1024w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8-768x512.jpg 768w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8-1536x1025.jpg 1536w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8-2048x1366.jpg 2048w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8-600x400.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" loading=\"eager\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e94a9f elementor-widget elementor-widget-heading\" data-id=\"9e94a9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccfd288 elementor-widget elementor-widget-text-editor\" data-id=\"ccfd288\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Agora Life si distingueva gi\u00e0 per la sua attenzione alla sostenibilit\u00e0 e alla qualit\u00e0, ma ora stiamo ampliando la collezione e la stiamo migliorando per <b>distinguerci da soli<\/b>. Il suo fascino principale risiede ora nelle texture, nei colori e nella versatilit\u00e0, che la rendono una scelta eccezionale, al di l\u00e0 dei suoi valori ambientali. <\/p><p style=\"text-align: center;\">Realizzato in <b>acrilico 100% tinto in massa e privo di PFAS<\/b>. La fibra riciclata, che costituisce tra <b>il 20%<\/b> e il <b>40% <\/b>della composizione, proviene dai nostri scarti di produzione. Questo processo rafforza il nostro <b>impegno verso la sostenibilit\u00e0<\/b> e il concetto di <b>circolarit\u00e0 <\/b>. Inoltre,<span style=\"font-size: 1rem;\"> gli scarti tessili vengono suddivisi in molti gruppi di colori diversi prima della lavorazione, consentendo il massimo controllo sulla tonalit\u00e0 finale. <\/span>   <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c3de7f e-flex e-con-boxed e-con e-parent\" data-id=\"8c3de7f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1d1633d e-con-full e-flex e-con e-child\" data-id=\"1d1633d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0ef8c9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e0ef8c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/it.agorafabrics.com\/tessuti\/life-liso\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visualizza la collezione<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14b7721 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"14b7721\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-10.jpg\" alt=\"Design senza titolo (10)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-11.jpg\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-12.jpg\" alt=\"Design senza titolo (12)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-9.jpg\" alt=\"Design senza titolo (9)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture Agora Life si distingueva gi\u00e0 per la sua attenzione alla sostenibilit\u00e0 e alla qualit\u00e0, ma ora stiamo ampliando la collezione e la stiamo migliorando per distinguerci da soli. Il suo fascino principale risiede ora nelle texture, nei colori e nella versatilit\u00e0, che la rendono una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[732,287],"tags":[],"sin-portada":[],"class_list":["post-16128","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agora-life","category-collezioni"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture - Agora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture - Agora\" \/>\n<meta property=\"og:description\" content=\"Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture Agora Life si distingueva gi\u00e0 per la sua attenzione alla sostenibilit\u00e0 e alla qualit\u00e0, ma ora stiamo ampliando la collezione e la stiamo migliorando per distinguerci da soli. Il suo fascino principale risiede ora nelle texture, nei colori e nella versatilit\u00e0, che la rendono una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/\" \/>\n<meta property=\"og:site_name\" content=\"Agora\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agorafabrics\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-30T11:24:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T14:32:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Agora Fabrics\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agora Fabrics\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\\\/\"},\"author\":{\"name\":\"Agora Fabrics\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/#\\\/schema\\\/person\\\/ae64a2daaa1a97f36b2fad01f14df23c\"},\"headline\":\"Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture\",\"datePublished\":\"2025-09-30T11:24:38+00:00\",\"dateModified\":\"2026-02-27T14:32:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\\\/\"},\"wordCount\":140,\"publisher\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Diseno-sin-titulo-8.jpg\",\"articleSection\":[\"Agora Life\",\"Collezioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\\\/\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\\\/\",\"name\":\"Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture - Agora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Diseno-sin-titulo-8.jpg\",\"datePublished\":\"2025-09-30T11:24:38+00:00\",\"dateModified\":\"2026-02-27T14:32:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agorafabrics.com\\\/it\\\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Diseno-sin-titulo-8.jpg\",\"contentUrl\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Diseno-sin-titulo-8.jpg\",\"width\":2560,\"height\":1708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/tessuti-da-esterno\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/\",\"name\":\"Agora\",\"description\":\"F\u00e1brica de tejidos y telas para exterior\",\"publisher\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/#organization\",\"name\":\"Tessuti Agora\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Agora-Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Agora-Logo.jpg\",\"width\":2292,\"height\":756,\"caption\":\"Tessuti Agora\"},\"image\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agorafabrics\\\/\",\"https:\\\/\\\/www.instagram.com\\\/agorafabrics\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tuvatextil\\\/\",\"https:\\\/\\\/vimeo.com\\\/user139090508\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6iNTVqBR6UsJBzO5OZTymw\",\"https:\\\/\\\/www.pinterest.es\\\/agorafabrics\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/it\\\/#\\\/schema\\\/person\\\/ae64a2daaa1a97f36b2fad01f14df23c\",\"name\":\"Agora Fabrics\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de19380d65cc648fc86cb15b26bc3ba1970506617d628a740205c34cb6b3e595?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de19380d65cc648fc86cb15b26bc3ba1970506617d628a740205c34cb6b3e595?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de19380d65cc648fc86cb15b26bc3ba1970506617d628a740205c34cb6b3e595?s=96&d=mm&r=g\",\"caption\":\"Agora Fabrics\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture - Agora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/","og_locale":"it_IT","og_type":"article","og_title":"Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture - Agora","og_description":"Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture Agora Life si distingueva gi\u00e0 per la sua attenzione alla sostenibilit\u00e0 e alla qualit\u00e0, ma ora stiamo ampliando la collezione e la stiamo migliorando per distinguerci da soli. Il suo fascino principale risiede ora nelle texture, nei colori e nella versatilit\u00e0, che la rendono una [&hellip;]","og_url":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/","og_site_name":"Agora","article_publisher":"https:\/\/www.facebook.com\/agorafabrics\/","article_published_time":"2025-09-30T11:24:38+00:00","article_modified_time":"2026-02-27T14:32:43+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8.jpg","type":"image\/jpeg"}],"author":"Agora Fabrics","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Agora Fabrics","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/#article","isPartOf":{"@id":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/"},"author":{"name":"Agora Fabrics","@id":"https:\/\/agorafabrics.com\/it\/#\/schema\/person\/ae64a2daaa1a97f36b2fad01f14df23c"},"headline":"Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture","datePublished":"2025-09-30T11:24:38+00:00","dateModified":"2026-02-27T14:32:43+00:00","mainEntityOfPage":{"@id":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/"},"wordCount":140,"publisher":{"@id":"https:\/\/agorafabrics.com\/it\/#organization"},"image":{"@id":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/#primaryimage"},"thumbnailUrl":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8.jpg","articleSection":["Agora Life","Collezioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/","url":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/","name":"Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture - Agora","isPartOf":{"@id":"https:\/\/agorafabrics.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/#primaryimage"},"image":{"@id":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/#primaryimage"},"thumbnailUrl":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8.jpg","datePublished":"2025-09-30T11:24:38+00:00","dateModified":"2026-02-27T14:32:43+00:00","breadcrumb":{"@id":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/#primaryimage","url":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8.jpg","contentUrl":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/09\/Diseno-sin-titulo-8.jpg","width":2560,"height":1708},{"@type":"BreadcrumbList","@id":"https:\/\/agorafabrics.com\/it\/stiamo-ampliando-la-collezione-agora-life-piu-texture-e-colori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agorafabrics.com\/it\/tessuti-da-esterno\/"},{"@type":"ListItem","position":2,"name":"Stiamo ampliando la collezione Agora LIFE: pi\u00f9 colori e texture"}]},{"@type":"WebSite","@id":"https:\/\/agorafabrics.com\/it\/#website","url":"https:\/\/agorafabrics.com\/it\/","name":"Agora","description":"F\u00e1brica de tejidos y telas para exterior","publisher":{"@id":"https:\/\/agorafabrics.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agorafabrics.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/agorafabrics.com\/it\/#organization","name":"Tessuti Agora","url":"https:\/\/agorafabrics.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/agorafabrics.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2024\/07\/Agora-Logo.jpg","contentUrl":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2024\/07\/Agora-Logo.jpg","width":2292,"height":756,"caption":"Tessuti Agora"},"image":{"@id":"https:\/\/agorafabrics.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agorafabrics\/","https:\/\/www.instagram.com\/agorafabrics\/","https:\/\/www.linkedin.com\/company\/tuvatextil\/","https:\/\/vimeo.com\/user139090508","https:\/\/www.youtube.com\/channel\/UC6iNTVqBR6UsJBzO5OZTymw","https:\/\/www.pinterest.es\/agorafabrics\/"]},{"@type":"Person","@id":"https:\/\/agorafabrics.com\/it\/#\/schema\/person\/ae64a2daaa1a97f36b2fad01f14df23c","name":"Agora Fabrics","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/de19380d65cc648fc86cb15b26bc3ba1970506617d628a740205c34cb6b3e595?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de19380d65cc648fc86cb15b26bc3ba1970506617d628a740205c34cb6b3e595?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de19380d65cc648fc86cb15b26bc3ba1970506617d628a740205c34cb6b3e595?s=96&d=mm&r=g","caption":"Agora Fabrics"}}]}},"_links":{"self":[{"href":"https:\/\/agorafabrics.com\/it\/wp-json\/wp\/v2\/posts\/16128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agorafabrics.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agorafabrics.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agorafabrics.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agorafabrics.com\/it\/wp-json\/wp\/v2\/comments?post=16128"}],"version-history":[{"count":0,"href":"https:\/\/agorafabrics.com\/it\/wp-json\/wp\/v2\/posts\/16128\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agorafabrics.com\/it\/wp-json\/wp\/v2\/media\/27874"}],"wp:attachment":[{"href":"https:\/\/agorafabrics.com\/it\/wp-json\/wp\/v2\/media?parent=16128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agorafabrics.com\/it\/wp-json\/wp\/v2\/categories?post=16128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agorafabrics.com\/it\/wp-json\/wp\/v2\/tags?post=16128"},{"taxonomy":"sin-portada","embeddable":true,"href":"https:\/\/agorafabrics.com\/it\/wp-json\/wp\/v2\/sin-portada?post=16128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}