{"id":24656,"date":"2025-10-01T10:28:39","date_gmt":"2025-10-01T08:28:39","guid":{"rendered":"https:\/\/agorafabrics.com\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/"},"modified":"2026-04-02T11:42:33","modified_gmt":"2026-04-02T09:42:33","slug":"wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta","status":"publish","type":"post","link":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/","title":{"rendered":"Wir wagen den Sprung nach S\u00fcdostasien: Er\u00f6ffnung einer neuen Repr\u00e4sentanz in Jakarta!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"24656\" class=\"elementor elementor-24656 elementor-16854\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4754139 e-flex e-con-boxed e-con e-parent\" data-id=\"4754139\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fcf42e6 elementor-widget elementor-widget-text-editor\" data-id=\"fcf42e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\"><strong>WIR WAGEN DEN SPRUNG NACH S\u00dcDOSTASIEN! <\/strong><\/h2><h2 style=\"text-align: center;\"><strong>Wir haben eine neue Repr\u00e4sentanz in Jakarta (Indonesien) er\u00f6ffnet.<\/strong><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86e38c8 elementor-widget elementor-widget-image\" data-id=\"86e38c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-6-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-19780 wvs-archive-product-image\" alt=\"\" srcset=\"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-6-768x512.jpg 768w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-6-300x200.jpg 300w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-6-1024x683.jpg 1024w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-6-1536x1025.jpg 1536w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-6-2048x1366.jpg 2048w, https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-6-600x400.jpg 600w\" sizes=\"(max-width: 768px) 100vw, 768px\" loading=\"eager\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05a8fe6 e-flex e-con-boxed e-con e-parent\" data-id=\"05a8fe6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e6de0b elementor-widget elementor-widget-text-editor\" data-id=\"0e6de0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Mit der Unterst\u00fctzung von ACCI\u00d3 st\u00e4rken wir unsere internationale Pr\u00e4senz und festigen die Marke auf den asiatischen M\u00e4rkten.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ea3b39 e-flex e-con-boxed e-con e-parent\" data-id=\"7ea3b39\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c112451 elementor-widget elementor-widget-text-editor\" data-id=\"c112451\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Wir freuen uns sehr, die Er\u00f6ffnung unseres ersten B\u00fcros in Jakarta (Indonesien) als Teil unseres Expansionsplans in Asien bekannt zu geben. Dieser neue strategische Punkt wird es uns erm\u00f6glichen, einen direkten technischen und kommerziellen Service mit lokalen Produzenten anzubieten, um die Synergien und die internationale Projektion der Marke als Synonym f\u00fcr Qualit\u00e4t zu verst\u00e4rken. <\/p><p style=\"text-align: center;\">Die Initiative wird unterst\u00fctzt durch das Programm<i>&#8222;Multilocalitzaci\u00f3 &#8211; Noves filials a l&#8217;estranger&#8220; von <\/i><a id=\"menur28v\" class=\"fui-Link ___1q1shib f2hkw1w f3rmtva f1ewtqcl fyind8e f1k6fduh f1w7gpdv fk6fouc fjoy568 figsok6 f1s184ao f1mk8lai fnbmjn9 f1o700av f13mvf36 f1cmlufx f9n3di6 f1ids18y f1tx3yz7 f1deo86v f1eh06m1 f1iescvh fhgqx19 f1olyrje f1p93eir f1nev41a f1h8hb77 f1lqvz6u f10aw75t fsle3fq f17ae5zn\" title=\"https:\/\/www.accio.gencat.cat\/ca\/serveis\/internacionalitzacio\/expansio-internacional\/ajuts-multilocalitzacio-noves-filials-a-l-estranger\/?utm_source=chatgpt.com\" href=\"https:\/\/www.accio.gencat.cat\/ca\/serveis\/internacionalitzacio\/expansio-internacional\/ajuts-multilocalitzacio-noves-filials-a-l-estranger\/?utm_source=chatgpt.com\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"V\u00ednculo ACCI\u00d3\"><i>ACCI\u00d3<\/i><\/a><i> <\/i>Die Initiative wird durch das Programm &#8222;Multilocalitzaci\u00f3 &#8211; Noves filials a l&#8217;estranger&#8220; von ACCI\u00d3 unterst\u00fctzt, das von der Generalitat de Catalunya gef\u00f6rdert wird und die Internationalisierung von Unternehmen mit globaler Ausrichtung unterst\u00fctzt.<\/p><p style=\"text-align: center;\">Mit dieser Er\u00f6ffnung festigt Agora Fabrics seine Pr\u00e4senz in S\u00fcdostasien und macht einen weiteren Schritt nach vorne in seiner Strategie, die Marke auf neue M\u00e4rkte zu bringen und sein Engagement f\u00fcr Qualit\u00e4t, N\u00e4he und Innovation zu st\u00e4rken.<\/p><p> <\/p><p> <\/p><p> <\/p><p> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>WIR WAGEN DEN SPRUNG NACH S\u00dcDOSTASIEN! Wir haben eine neue Repr\u00e4sentanz in Jakarta (Indonesien) er\u00f6ffnet. Mit der Unterst\u00fctzung von ACCI\u00d3 st\u00e4rken wir unsere internationale Pr\u00e4senz und festigen die Marke auf den asiatischen M\u00e4rkten. Wir freuen uns sehr, die Er\u00f6ffnung unseres ersten B\u00fcros in Jakarta (Indonesien) als Teil unseres Expansionsplans in Asien bekannt zu geben. Dieser [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1125],"tags":[],"sin-portada":[],"class_list":["post-24656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prasentation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wir wagen den Sprung nach S\u00fcdostasien: Er\u00f6ffnung einer neuen Repr\u00e4sentanz in Jakarta! - Agora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wir wagen den Sprung nach S\u00fcdostasien: Er\u00f6ffnung einer neuen Repr\u00e4sentanz in Jakarta! - Agora\" \/>\n<meta property=\"og:description\" content=\"WIR WAGEN DEN SPRUNG NACH S\u00dcDOSTASIEN! Wir haben eine neue Repr\u00e4sentanz in Jakarta (Indonesien) er\u00f6ffnet. Mit der Unterst\u00fctzung von ACCI\u00d3 st\u00e4rken wir unsere internationale Pr\u00e4senz und festigen die Marke auf den asiatischen M\u00e4rkten. Wir freuen uns sehr, die Er\u00f6ffnung unseres ersten B\u00fcros in Jakarta (Indonesien) als Teil unseres Expansionsplans in Asien bekannt zu geben. Dieser [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/\" \/>\n<meta property=\"og:site_name\" content=\"Agora\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/agorafabrics\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-01T08:28:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-02T09:42:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Agora Fabrics\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agora Fabrics\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\\\/\"},\"author\":{\"name\":\"Agora Fabrics\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#\\\/schema\\\/person\\\/ae64a2daaa1a97f36b2fad01f14df23c\"},\"headline\":\"Wir wagen den Sprung nach S\u00fcdostasien: Er\u00f6ffnung einer neuen Repr\u00e4sentanz in Jakarta!\",\"datePublished\":\"2025-10-01T08:28:39+00:00\",\"dateModified\":\"2026-04-02T09:42:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\\\/\"},\"wordCount\":213,\"publisher\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Mailchimp-2-1-1.jpg\",\"articleSection\":[\"Pr\u00e4sentation\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\\\/\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\\\/\",\"name\":\"Wir wagen den Sprung nach S\u00fcdostasien: Er\u00f6ffnung einer neuen Repr\u00e4sentanz in Jakarta! - Agora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Mailchimp-2-1-1.jpg\",\"datePublished\":\"2025-10-01T08:28:39+00:00\",\"dateModified\":\"2026-04-02T09:42:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agorafabrics.com\\\/de\\\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Mailchimp-2-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Mailchimp-2-1-1.jpg\",\"width\":2560,\"height\":1708},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wir wagen den Sprung nach S\u00fcdostasien: Er\u00f6ffnung einer neuen Repr\u00e4sentanz in Jakarta!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/\",\"name\":\"Agora\",\"description\":\"F\u00e1brica de tejidos y telas para exterior\",\"publisher\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#organization\",\"name\":\"Agora-Stoffe\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Agora-Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Agora-Logo.jpg\",\"width\":2292,\"height\":756,\"caption\":\"Agora-Stoffe\"},\"image\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agorafabrics\\\/\",\"https:\\\/\\\/www.instagram.com\\\/agorafabrics\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tuvatextil\\\/\",\"https:\\\/\\\/vimeo.com\\\/user139090508\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6iNTVqBR6UsJBzO5OZTymw\",\"https:\\\/\\\/www.pinterest.es\\\/agorafabrics\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#\\\/schema\\\/person\\\/ae64a2daaa1a97f36b2fad01f14df23c\",\"name\":\"Agora Fabrics\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de19380d65cc648fc86cb15b26bc3ba1970506617d628a740205c34cb6b3e595?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de19380d65cc648fc86cb15b26bc3ba1970506617d628a740205c34cb6b3e595?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de19380d65cc648fc86cb15b26bc3ba1970506617d628a740205c34cb6b3e595?s=96&d=mm&r=g\",\"caption\":\"Agora Fabrics\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wir wagen den Sprung nach S\u00fcdostasien: Er\u00f6ffnung einer neuen Repr\u00e4sentanz in Jakarta! - Agora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/","og_locale":"de_DE","og_type":"article","og_title":"Wir wagen den Sprung nach S\u00fcdostasien: Er\u00f6ffnung einer neuen Repr\u00e4sentanz in Jakarta! - Agora","og_description":"WIR WAGEN DEN SPRUNG NACH S\u00dcDOSTASIEN! Wir haben eine neue Repr\u00e4sentanz in Jakarta (Indonesien) er\u00f6ffnet. Mit der Unterst\u00fctzung von ACCI\u00d3 st\u00e4rken wir unsere internationale Pr\u00e4senz und festigen die Marke auf den asiatischen M\u00e4rkten. Wir freuen uns sehr, die Er\u00f6ffnung unseres ersten B\u00fcros in Jakarta (Indonesien) als Teil unseres Expansionsplans in Asien bekannt zu geben. Dieser [&hellip;]","og_url":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/","og_site_name":"Agora","article_publisher":"https:\/\/www.facebook.com\/agorafabrics\/","article_published_time":"2025-10-01T08:28:39+00:00","article_modified_time":"2026-04-02T09:42:33+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-1-1.jpg","type":"image\/jpeg"}],"author":"Agora Fabrics","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Agora Fabrics","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/#article","isPartOf":{"@id":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/"},"author":{"name":"Agora Fabrics","@id":"https:\/\/agorafabrics.com\/de\/#\/schema\/person\/ae64a2daaa1a97f36b2fad01f14df23c"},"headline":"Wir wagen den Sprung nach S\u00fcdostasien: Er\u00f6ffnung einer neuen Repr\u00e4sentanz in Jakarta!","datePublished":"2025-10-01T08:28:39+00:00","dateModified":"2026-04-02T09:42:33+00:00","mainEntityOfPage":{"@id":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/"},"wordCount":213,"publisher":{"@id":"https:\/\/agorafabrics.com\/de\/#organization"},"image":{"@id":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/#primaryimage"},"thumbnailUrl":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-1-1.jpg","articleSection":["Pr\u00e4sentation"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/","url":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/","name":"Wir wagen den Sprung nach S\u00fcdostasien: Er\u00f6ffnung einer neuen Repr\u00e4sentanz in Jakarta! - Agora","isPartOf":{"@id":"https:\/\/agorafabrics.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/#primaryimage"},"image":{"@id":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/#primaryimage"},"thumbnailUrl":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-1-1.jpg","datePublished":"2025-10-01T08:28:39+00:00","dateModified":"2026-04-02T09:42:33+00:00","breadcrumb":{"@id":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/#primaryimage","url":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-1-1.jpg","contentUrl":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2025\/10\/Mailchimp-2-1-1.jpg","width":2560,"height":1708},{"@type":"BreadcrumbList","@id":"https:\/\/agorafabrics.com\/de\/wir-wagen-den-sprung-nach-suedostasien-eroeffnung-einer-neuen-repraesentanz-in-jakarta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agorafabrics.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Wir wagen den Sprung nach S\u00fcdostasien: Er\u00f6ffnung einer neuen Repr\u00e4sentanz in Jakarta!"}]},{"@type":"WebSite","@id":"https:\/\/agorafabrics.com\/de\/#website","url":"https:\/\/agorafabrics.com\/de\/","name":"Agora","description":"F\u00e1brica de tejidos y telas para exterior","publisher":{"@id":"https:\/\/agorafabrics.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agorafabrics.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/agorafabrics.com\/de\/#organization","name":"Agora-Stoffe","url":"https:\/\/agorafabrics.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/agorafabrics.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2024\/07\/Agora-Logo.jpg","contentUrl":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2024\/07\/Agora-Logo.jpg","width":2292,"height":756,"caption":"Agora-Stoffe"},"image":{"@id":"https:\/\/agorafabrics.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agorafabrics\/","https:\/\/www.instagram.com\/agorafabrics\/","https:\/\/www.linkedin.com\/company\/tuvatextil\/","https:\/\/vimeo.com\/user139090508","https:\/\/www.youtube.com\/channel\/UC6iNTVqBR6UsJBzO5OZTymw","https:\/\/www.pinterest.es\/agorafabrics\/"]},{"@type":"Person","@id":"https:\/\/agorafabrics.com\/de\/#\/schema\/person\/ae64a2daaa1a97f36b2fad01f14df23c","name":"Agora Fabrics","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/de19380d65cc648fc86cb15b26bc3ba1970506617d628a740205c34cb6b3e595?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de19380d65cc648fc86cb15b26bc3ba1970506617d628a740205c34cb6b3e595?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de19380d65cc648fc86cb15b26bc3ba1970506617d628a740205c34cb6b3e595?s=96&d=mm&r=g","caption":"Agora Fabrics"}}]}},"_links":{"self":[{"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/posts\/24656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/comments?post=24656"}],"version-history":[{"count":1,"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/posts\/24656\/revisions"}],"predecessor-version":[{"id":28580,"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/posts\/24656\/revisions\/28580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/media\/27816"}],"wp:attachment":[{"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/media?parent=24656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/categories?post=24656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/tags?post=24656"},{"taxonomy":"sin-portada","embeddable":true,"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/sin-portada?post=24656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}