{"id":1131,"count":2,"description":"","link":"https:\/\/agorafabrics.com\/de\/category\/agora-unterschrift-serie\/","name":"Agora Unterschrift Serie","slug":"agora-unterschrift-serie","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agora Unterschrift Serie archivos - Agora<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agora Unterschrift Serie archivos - Agora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agorafabrics.com\/de\/category\/agora-unterschrift-serie\/\" \/>\n<meta property=\"og:site_name\" content=\"Agora\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/category\\\/agora-unterschrift-serie\\\/\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/category\\\/agora-unterschrift-serie\\\/\",\"name\":\"Agora Unterschrift Serie archivos - Agora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/category\\\/agora-unterschrift-serie\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/category\\\/agora-unterschrift-serie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agora Unterschrift Serie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/\",\"name\":\"Agora\",\"description\":\"F\u00e1brica de tejidos y telas para exterior\",\"publisher\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#organization\",\"name\":\"Agora-Stoffe\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Agora-Logo.jpg\",\"contentUrl\":\"https:\\\/\\\/agorafabrics.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Agora-Logo.jpg\",\"width\":2292,\"height\":756,\"caption\":\"Agora-Stoffe\"},\"image\":{\"@id\":\"https:\\\/\\\/agorafabrics.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/agorafabrics\\\/\",\"https:\\\/\\\/www.instagram.com\\\/agorafabrics\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tuvatextil\\\/\",\"https:\\\/\\\/vimeo.com\\\/user139090508\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6iNTVqBR6UsJBzO5OZTymw\",\"https:\\\/\\\/www.pinterest.es\\\/agorafabrics\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agora Unterschrift Serie archivos - Agora","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Agora Unterschrift Serie archivos - Agora","og_url":"https:\/\/agorafabrics.com\/de\/category\/agora-unterschrift-serie\/","og_site_name":"Agora","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/agorafabrics.com\/de\/category\/agora-unterschrift-serie\/","url":"https:\/\/agorafabrics.com\/de\/category\/agora-unterschrift-serie\/","name":"Agora Unterschrift Serie archivos - Agora","isPartOf":{"@id":"https:\/\/agorafabrics.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/agorafabrics.com\/de\/category\/agora-unterschrift-serie\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/agorafabrics.com\/de\/category\/agora-unterschrift-serie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/agorafabrics.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Agora Unterschrift Serie"}]},{"@type":"WebSite","@id":"https:\/\/agorafabrics.com\/de\/#website","url":"https:\/\/agorafabrics.com\/de\/","name":"Agora","description":"F\u00e1brica de tejidos y telas para exterior","publisher":{"@id":"https:\/\/agorafabrics.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agorafabrics.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/agorafabrics.com\/de\/#organization","name":"Agora-Stoffe","url":"https:\/\/agorafabrics.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/agorafabrics.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2024\/07\/Agora-Logo.jpg","contentUrl":"https:\/\/agorafabrics.com\/wp-content\/uploads\/2024\/07\/Agora-Logo.jpg","width":2292,"height":756,"caption":"Agora-Stoffe"},"image":{"@id":"https:\/\/agorafabrics.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/agorafabrics\/","https:\/\/www.instagram.com\/agorafabrics\/","https:\/\/www.linkedin.com\/company\/tuvatextil\/","https:\/\/vimeo.com\/user139090508","https:\/\/www.youtube.com\/channel\/UC6iNTVqBR6UsJBzO5OZTymw","https:\/\/www.pinterest.es\/agorafabrics\/"]}]}},"_links":{"self":[{"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/categories\/1131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/agorafabrics.com\/de\/wp-json\/wp\/v2\/posts?categories=1131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}